{"id":6505,"date":"2023-10-07T05:51:21","date_gmt":"2023-10-07T12:51:21","guid":{"rendered":"https:\/\/www.sriperiyavadosabhavan.ca\/order-online\/product\/rava-spicy-masala-dosa\/"},"modified":"2023-10-07T05:51:21","modified_gmt":"2023-10-07T12:51:21","slug":"rava-spicy-masala-dosa","status":"publish","type":"product","link":"https:\/\/www.sriperiyavadosabhavan.ca\/order-online\/product\/rava-spicy-masala-dosa\/","title":{"rendered":"RAVA SPICY MASALA DOSA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Thin crepe from cream of wheat lathered with special ex spicy paste and stuffed with mashed potatoes<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"product_cat":[189],"product_tag":[],"_links":{"self":[{"href":"https:\/\/www.sriperiyavadosabhavan.ca\/order-online\/wp-json\/wp\/v2\/product\/6505"}],"collection":[{"href":"https:\/\/www.sriperiyavadosabhavan.ca\/order-online\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.sriperiyavadosabhavan.ca\/order-online\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.sriperiyavadosabhavan.ca\/order-online\/wp-json\/wp\/v2\/media?parent=6505"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.sriperiyavadosabhavan.ca\/order-online\/wp-json\/wp\/v2\/product_cat?post=6505"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.sriperiyavadosabhavan.ca\/order-online\/wp-json\/wp\/v2\/product_tag?post=6505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}